{"id":1401,"date":"2023-11-14T09:56:13","date_gmt":"2023-11-14T08:56:13","guid":{"rendered":"https:\/\/compliancebonatti.com\/compliance\/?p=1401"},"modified":"2023-11-23T13:44:52","modified_gmt":"2023-11-23T12:44:52","slug":"los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo","status":"publish","type":"post","link":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/","title":{"rendered":"Los 4 errores m\u00e1s comunes al elegir un experto externo en prevenci\u00f3n del blanqueo"},"content":{"rendered":"<p style=\"text-align: justify;\">Los errores siempre pasan factura, pero m\u00e1s los cometidos en el terreno empresarial. \u00c9stos pueden traducirse en problemas graves, especialmente, cuando tienen que ver con temas relacionados con el compliance y el blanqueo de capitales y es que independientemente del tama\u00f1o de la empresa, cualquier compa\u00f1\u00eda debe dedicar una enorme cantidad de tiempo y esfuerzo en cumplir con la legislaci\u00f3n vigente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.linkedin.com\/in\/francisco-bonatti-abogado-delito-blanqueo-capitales-compliance\/\" target=\"_blank\" rel=\"noopener\">Francisco Bonatti,<\/a> socio director de <a href=\"https:\/\/compliancebonatti.com\/compliance\/\">Bonatti Compliance<\/a>, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo de Capitales es una pr\u00e1ctica que muchas compa\u00f1\u00edas toman a la ligera y quieren hacer de forma r\u00e1pida, pero cuyo desd\u00e9n puede costarles millones si ignoran la totalidad y la complejidad de los requerimientos a los que deben hacer frente\u201d.<\/p>\n<p style=\"text-align: justify;\">Es por ello por lo que es esencial que las compa\u00f1\u00edas adopten medidas y los procesos adecuados para evitar la graves sanciones administrativas y penales.\u00a0<strong>Francisco Bonatti<\/strong>\u00a0destaca que \u201cno existe mejor defensa para la empresa que la prevenci\u00f3n\u201d. En este sentido, este experto explica que el papel del Experto Externo en Prevenci\u00f3n de Blanqueo es fundamental para evitar da\u00f1os econ\u00f3micos y reputaciones en las empresas.<\/p>\n<h2><strong>\u00bfCU\u00c1LES SON LOS ERRORES M\u00c1S COMUNES QUE PUEDEN COMETER LOS SUJETOS OBLIGADOS A LA HORA DE ELEGIR EXPERTO EXTERNO?<\/strong><\/h2>\n<p style=\"text-align: justify;\">Desde Bonatti Compliance se\u00f1alan los cuatro errores m\u00e1s comunes que suelen cometer las empresas a la hora de seleccionar a los Expertos Externos en Prevenci\u00f3n de Blanqueo:<\/p>\n<p style=\"text-align: justify;\">1.-\u00a0<strong>Seleccionar un auditor que carece del nivel de independencia e imparcialidad necesarios<\/strong>: esto suele ser consecuencia fundamentalmente de vinculaciones comerciales o de otro tipo que pueden existir entre la organizaci\u00f3n que oferta el servicio de auditoria y el cliente. Por ejemplo, servicios anteriores o posteriores de formaci\u00f3n o consultor\u00eda en materia de Prevenci\u00f3n de Blanqueo (prohibidos en los dos a\u00f1os anteriores o posteriores a la emisi\u00f3n del informe), o bien por otro tipo de relaciones, incluso no vinculadas a la prevenci\u00f3n del blanqueo (como servicios de defensa procesal, consultor\u00eda financiera o fiscal). Otro riesgo es que la organizaci\u00f3n que oferta el servicio de auditoria tenga un nivel de autonom\u00eda e independencia formalmente correcto, pero el Experto Externo auditor no asegure el mismo nivel o pueda mantener alg\u00fan tipo de conflicto de intereses con el Sujeto Obligado a auditar que afecte a su propia autonom\u00eda e independencia.<\/p>\n<p style=\"text-align: justify;\">2.-\u00a0<strong>Escoger un auditor que se deje condicionar en su trabajo por presiones comerciales internas o externas<\/strong>: esto suele dar como resultados informes de baja calidad que pueden ser objeto de sanci\u00f3n por las autoridades. Estas circunstancias se producen en ocasiones por ceder ante la presi\u00f3n de clientes que condicionan la selecci\u00f3n de su auditor de criterios de precio del servicio, en otras ocasiones por necesidades de la empresa del Experto Externo que est\u00e1 sometida a los vaivenes del mercado y puede necesitar facturar o que quiere introducirse en un sector que no conoce o captar un nuevo cliente, o carece de auditores espec\u00edficos para ese perfil de cliente y calcula mal o rebaja voluntariamente los tiempos y costes que ser\u00edan razonables en su oferta, como un incentivo para asegurar que el cliente acepte su contrataci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">3.-\u00a0<strong>Elegir un auditor que no tiene procedimentado su servicio de auditoria<\/strong>: un buen servicio se establece mediante un manual que establezca criterios claros, con formatos, instrucciones y procedimientos ajustados a las normas legales y requisitos aplicables. Correr el riesgo de hacerlo sin \u00e9l puede conllevar informes que omiten aspectos cr\u00edticos del Sujeto Obligado auditado, que no generan evidencias de sus muestreos y pruebas sustantivas o se equivocan en el alcance de la auditoria, generando con ello un grave riesgo de sanciones por las autoridades.<\/p>\n<p style=\"text-align: justify;\">4.-\u00a0<strong>Optar por un auditor gui\u00e1ndose por sus acciones comerciales o de marca, sin aplicar al proceso de selecci\u00f3n la diligencia debida exigible<\/strong>: hasta la fecha no exist\u00eda una referencia externa y objetiva que sirviera a los sujetos obligados para seleccionar a la entidad o experto externo que iba a realizarles su informe. De este modo, el sujeto obligado depend\u00eda exclusivamente de las capacidades t\u00e9cnicas y conocimientos del mercado que ten\u00eda su propio personal para realizar las selecciones de candidatos y aplicarles el correspondiente procedimiento de Diligencia Debida. En este contexto, la selecci\u00f3n se hac\u00eda en base a las acciones comerciales, reputacionales o de marca que desarrollaban los candidatos (presumiendo por ello que son competentes, independientes e imparciales), o bien fi\u00e1ndose de la relaci\u00f3n de clientes a quienes el candidato pudiera haber prestado servicios. Frente a los enormes riesgos que entra\u00f1a este m\u00e9todo de selecci\u00f3n, las Entidades acreditadas aportan con el sello de ENAC la garant\u00eda que la Entidad Nacional de Acreditaci\u00f3n las eval\u00faa de forma peri\u00f3dica, asegurando a trav\u00e9s de las auditorias que la estructura y organizaci\u00f3n interna de las entidades acreditadas, as\u00ed como su personal, sistema de gesti\u00f3n y sistema calidad cumplen con la normativa legal y con el est\u00e1ndar establecido por ENAC a trav\u00e9s de sus criterios espec\u00edficos para la Acreditaci\u00f3n.<\/p>\n<p>Puedes leer noticia <a href=\"https:\/\/www.denoticias.es\/negocios\/errores-externo-prevencion-del-blanqueo.html\">aqu\u00ed\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los errores siempre pasan factura, pero m\u00e1s los cometidos en el terreno empresarial. \u00c9stos pueden traducirse en problemas graves, especialmente, cuando tienen que ver con temas relacionados con el compliance y el blanqueo de capitales y es que independientemente del tama\u00f1o de la empresa, cualquier compa\u00f1\u00eda debe dedicar una enorme cantidad de tiempo y esfuerzo [&#8230;]\n","protected":false},"author":2,"featured_media":1404,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[25,53],"class_list":["post-1401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blanqueo-de-capitales","tag-blanqueo-de-capitales","tag-experto-externo-en-pbcft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo<\/title>\n<meta name=\"description\" content=\"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo\" \/>\n<meta property=\"og:description\" content=\"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonatti Compliance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T08:56:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T12:44:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bonatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BonattiComply\" \/>\n<meta name=\"twitter:site\" content=\"@BonattiComply\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bonatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\"},\"author\":{\"name\":\"bonatti\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b\"},\"headline\":\"Los 4 errores m\u00e1s comunes al elegir un experto externo en prevenci\u00f3n del blanqueo\",\"datePublished\":\"2023-11-14T08:56:13+00:00\",\"dateModified\":\"2023-11-23T12:44:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\"},\"wordCount\":898,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png\",\"keywords\":[\"Blanqueo de capitales\",\"Experto Externo en PBCFT\"],\"articleSection\":[\"Blanqueo de capitales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\",\"name\":\"Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo\",\"isPartOf\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png\",\"datePublished\":\"2023-11-14T08:56:13+00:00\",\"dateModified\":\"2023-11-23T12:44:52+00:00\",\"description\":\"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...\",\"breadcrumb\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png\",\"contentUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png\",\"width\":560,\"height\":315,\"caption\":\"LOS 4 ERRORES M\u00c1S COMUNES AL ELEGIR UN EXPERTO EXTERNO EN PREVENCI\u00d3N DEL BLANQUEO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/compliancebonatti.com\/compliance\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los 4 errores m\u00e1s comunes al elegir un experto externo en prevenci\u00f3n del blanqueo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#website\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/\",\"name\":\"Bonatti Compliance\",\"description\":\"Consultor\u00eda Compliance para empresas\",\"publisher\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compliancebonatti.com\/compliance\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\",\"name\":\"Bonatti Compliance SLP\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png\",\"contentUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png\",\"width\":600,\"height\":40,\"caption\":\"Bonatti Compliance SLP\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/\",\"https:\/\/x.com\/BonattiComply\",\"https:\/\/www.instagram.com\/bonatticompliance\/\",\"https:\/\/www.linkedin.com\/company\/bonatti-compliance\/about\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b\",\"name\":\"bonatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g\",\"caption\":\"bonatti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo","description":"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/","og_locale":"es_ES","og_type":"article","og_title":"Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo","og_description":"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...","og_url":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/","og_site_name":"Bonatti Compliance","article_publisher":"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/","article_published_time":"2023-11-14T08:56:13+00:00","article_modified_time":"2023-11-23T12:44:52+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png","type":"image\/png"}],"author":"bonatti","twitter_card":"summary_large_image","twitter_creator":"@BonattiComply","twitter_site":"@BonattiComply","twitter_misc":{"Escrito por":"bonatti","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#article","isPartOf":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/"},"author":{"name":"bonatti","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b"},"headline":"Los 4 errores m\u00e1s comunes al elegir un experto externo en prevenci\u00f3n del blanqueo","datePublished":"2023-11-14T08:56:13+00:00","dateModified":"2023-11-23T12:44:52+00:00","mainEntityOfPage":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/"},"wordCount":898,"commentCount":0,"publisher":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#organization"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage"},"thumbnailUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png","keywords":["Blanqueo de capitales","Experto Externo en PBCFT"],"articleSection":["Blanqueo de capitales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/","url":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/","name":"Errores al elegir Experto Externo en prevenci\u00f3n del blanqueo","isPartOf":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#website"},"primaryImageOfPage":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage"},"thumbnailUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png","datePublished":"2023-11-14T08:56:13+00:00","dateModified":"2023-11-23T12:44:52+00:00","description":"Francisco Bonatti, socio de Bonatti Compliance, se\u00f1ala al respecto que \u201cel cumplimiento de la legislaci\u00f3n en Prevenci\u00f3n del Blanqueo...","breadcrumb":{"@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#primaryimage","url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png","contentUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2023\/11\/Compliance-Articulo-.png","width":560,"height":315,"caption":"LOS 4 ERRORES M\u00c1S COMUNES AL ELEGIR UN EXPERTO EXTERNO EN PREVENCI\u00d3N DEL BLANQUEO"},{"@type":"BreadcrumbList","@id":"https:\/\/compliancebonatti.com\/compliance\/los-4-errores-mas-comunes-al-elegir-un-experto-externo-en-prevencion-del-blanqueo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/compliancebonatti.com\/compliance\/"},{"@type":"ListItem","position":2,"name":"Los 4 errores m\u00e1s comunes al elegir un experto externo en prevenci\u00f3n del blanqueo"}]},{"@type":"WebSite","@id":"https:\/\/compliancebonatti.com\/compliance\/#website","url":"https:\/\/compliancebonatti.com\/compliance\/","name":"Bonatti Compliance","description":"Consultor\u00eda Compliance para empresas","publisher":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compliancebonatti.com\/compliance\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/compliancebonatti.com\/compliance\/#organization","name":"Bonatti Compliance SLP","url":"https:\/\/compliancebonatti.com\/compliance\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/","url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png","contentUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png","width":600,"height":40,"caption":"Bonatti Compliance SLP"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/","https:\/\/x.com\/BonattiComply","https:\/\/www.instagram.com\/bonatticompliance\/","https:\/\/www.linkedin.com\/company\/bonatti-compliance\/about\/"]},{"@type":"Person","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b","name":"bonatti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g","caption":"bonatti"}}]}},"_links":{"self":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/1401"}],"collection":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":5,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/1401\/revisions"}],"predecessor-version":[{"id":1407,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/1401\/revisions\/1407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/media\/1404"}],"wp:attachment":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/media?parent=1401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/categories?post=1401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/tags?post=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}