{"id":869,"date":"2021-04-17T19:14:27","date_gmt":"2021-04-17T17:14:27","guid":{"rendered":"https:\/\/compliancebonatti.com\/compliance\/?p=869"},"modified":"2024-06-06T15:51:59","modified_gmt":"2024-06-06T13:51:59","slug":"competencia-tecnica-expertos-externos-blanqueo-capitales","status":"publish","type":"post","link":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/","title":{"rendered":"Capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados"},"content":{"rendered":"<h2><strong><u>Capacidad y competencia t\u00e9cnica del Experto Externo y del equipo auditor<\/u><\/strong><\/h2>\n<p>La capacidad y competencia t\u00e9cnica del Experto Externo es un tema al que se hace menci\u00f3n expresa en<a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2010-6737#a28\" target=\"_blank\" rel=\"noopener noreferrer\"> el Art 28 de la ley 10\/2010<\/a>, el <a href=\"https:\/\/www.enac.es\/documents\/7020\/8dc7e89e-8d11-4c63-8824-a1ad05633012?version=2.0\" target=\"_blank\" rel=\"noopener noreferrer\">CEA-ENAC 25<\/a> define con suficiente detalle el grado de formaci\u00f3n y experiencia profesional que deben acreditar \u00a0los expertos externos.<\/p>\n<p>El experto externo deber\u00e1 demostrar conocimiento en -al menos- los siguientes \u00e1mbitos de la PBC-FT:<\/p>\n<ul>\n<li>Legislaci\u00f3n nacional e internacional aplicable a la prevenci\u00f3n del blanqueo de capitales, la financiaci\u00f3n del terrorismo y el control de los medios de pago.<\/li>\n<li>Est\u00e1ndares internacionales aplicables a la prevenci\u00f3n del blanqueo de capitales y la financiaci\u00f3n del terrorismo, incluyendo gu\u00edas de buenas pr\u00e1cticas, cat\u00e1logos de operaciones de riesgo y recomendaciones emitidas por reguladores nacionales e internacionales y organizaciones nacionales e internacionales relacionadas con la prevenci\u00f3n del blanqueo de capitales y la financiaci\u00f3n del terrorismo.<\/li>\n<li>Metodolog\u00edas de identificaci\u00f3n, evaluaci\u00f3n y gesti\u00f3n del riesgo y las operaciones sospechosas de blanqueo de capitales o financiaci\u00f3n del terrorismo.<\/li>\n<li>Fundamentos jur\u00eddicos que permitan comprender suficientemente la naturaleza jur\u00eddica y regulaci\u00f3n b\u00e1sica de los clientes que son objeto de examen.<\/li>\n<li>Fenomenolog\u00eda del blanqueo de capitales y la financiaci\u00f3n del terrorismo.<\/li>\n<li>T\u00e9cnicas y metodolog\u00edas de auditor\u00eda y control interno, incluyendo fundamentos de muestreo.<\/li>\n<li>Regulaci\u00f3n de la organizaci\u00f3n institucional supervisora de los clientes.<\/li>\n<li>Medidas preventivas y metodolog\u00edas de control interno en prevenci\u00f3n del blanqueo de capitales y la financiaci\u00f3n del terrorismo.<\/li>\n<li>Incidencia en la <a href=\"https:\/\/compliancebonatti.com\/compliance\/servicios-responsabilidad-y-sostenibilidad\/\">prevenci\u00f3n del blanqueo de capitales<\/a> y la financiaci\u00f3n del terrorismo del delito de blanqueo de capitales y sus delitos subyacentes y del delito de financiaci\u00f3n del terrorismo.<\/li>\n<li>T\u00e9cnicas de elaboraci\u00f3n del informe del experto externo.<\/li>\n<\/ul>\n<p>Para el resto del personal que el organismo de inspecci\u00f3n va a incorporar en el equipo auditor, \u00e9ste debe establecer las competencias exigibles seg\u00fan la actividad de soporte al experto externo que van a realizar dentro del equipo, teniendo en cuenta lo establecido en el punto anterior.<\/p>\n<p>El organismo de inspecci\u00f3n debe disponer de un procedimiento para la contrataci\u00f3n del equipo auditor que realiza los ex\u00e1menes externos, de modo que se asegure y garantice a sus clientes la idoneidad de dicho equipo.<\/p>\n<p>El organismo de inspecci\u00f3n debe mantener registros que evidencien que los evaluadores que pretendan actuar como expertos externos han presentado el f<a href=\"https:\/\/www.sepblac.es\/es\/expertos-externos\/tramites\/\" target=\"_blank\" rel=\"noopener noreferrer\">ormulario F22-7 al Servicio Ejecutivo<\/a> de la Comisi\u00f3n antes de iniciar su actividad.<\/p>\n<p>La entidad de inspecci\u00f3n deber\u00eda poder acreditar que todos ellos han recibido formaci\u00f3n adecuada sobre el Sistema de Inspecci\u00f3n y el papel que desempe\u00f1an en el mismo, no solo desde una perspectiva t\u00e9cnica, sino tambi\u00e9n en cuanto a los compromisos contractuales relativos a independencia, confidencialidad, etc.<\/p>\n<p>Deber\u00eda poder acreditar procesos de formaci\u00f3n y mejora continua de los t\u00e9cnicos y auditores y asegurar que los expertos externos cumplen con sus obligaciones de inscripci\u00f3n e informaci\u00f3n al SEPBLAC.<\/p>\n<p>Deber\u00eda poder acreditar que hay un proceso de evaluaci\u00f3n del desempe\u00f1o de sus t\u00e9cnicos, expertos, auditores y empleados vinculados al Sistema de Inspecci\u00f3n, mediante procedimientos adecuados de diligencia debida interna.<\/p>\n<p>El organismo de inspecci\u00f3n deber\u00eda ser capaz de acreditar que todo el personal mantiene est\u00e1ndares \u00e9ticos acordes con las exigencias\u00a0 recogidas para el personal de los Sujetos obligados en materia de PBC-FT y que observa sus deberes de confidencialidad.<\/p>\n<p>Debe ser capaz de acreditar que dispone de los recursos t\u00e9cnicos (hardware y software) necesarios para el correcto desempe\u00f1o del sistema de inspecci\u00f3n y que su seguridad y estado t\u00e9cnico son conformes con el Sistema de Inspecci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capacidad y competencia t\u00e9cnica del Experto Externo y del equipo auditor La capacidad y competencia t\u00e9cnica del Experto Externo es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley 10\/2010, el CEA-ENAC 25 define con suficiente detalle el grado de formaci\u00f3n y experiencia profesional que deben acreditar \u00a0los expertos [&#8230;]\n","protected":false},"author":2,"featured_media":860,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,3],"tags":[],"class_list":["post-869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blanqueo-de-capitales","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Competencia t\u00e9cnica de los Expertos Externos acreditados<\/title>\n<meta name=\"description\" content=\"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencia t\u00e9cnica de los Expertos Externos acreditados\" \/>\n<meta property=\"og:description\" content=\"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonatti Compliance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T17:14:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T13:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bonatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BonattiComply\" \/>\n<meta name=\"twitter:site\" content=\"@BonattiComply\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bonatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\"},\"author\":{\"name\":\"bonatti\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b\"},\"headline\":\"Capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados\",\"datePublished\":\"2021-04-17T17:14:27+00:00\",\"dateModified\":\"2024-06-06T13:51:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\"},\"wordCount\":651,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png\",\"articleSection\":[\"Blanqueo de capitales\",\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\",\"name\":\"Competencia t\u00e9cnica de los Expertos Externos acreditados\",\"isPartOf\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png\",\"datePublished\":\"2021-04-17T17:14:27+00:00\",\"dateModified\":\"2024-06-06T13:51:59+00:00\",\"description\":\"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...\",\"breadcrumb\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png\",\"contentUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png\",\"width\":560,\"height\":315,\"caption\":\"Competencia t\u00e9cnica experto externo ENAC Bonatti Blanqueo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/compliancebonatti.com\/compliance\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#website\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/\",\"name\":\"Bonatti Compliance\",\"description\":\"Consultor\u00eda Compliance para empresas\",\"publisher\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compliancebonatti.com\/compliance\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#organization\",\"name\":\"Bonatti Compliance SLP\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png\",\"contentUrl\":\"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png\",\"width\":600,\"height\":40,\"caption\":\"Bonatti Compliance SLP\"},\"image\":{\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/\",\"https:\/\/x.com\/BonattiComply\",\"https:\/\/www.instagram.com\/bonatticompliance\/\",\"https:\/\/www.linkedin.com\/company\/bonatti-compliance\/about\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b\",\"name\":\"bonatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g\",\"caption\":\"bonatti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competencia t\u00e9cnica de los Expertos Externos acreditados","description":"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/","og_locale":"es_ES","og_type":"article","og_title":"Competencia t\u00e9cnica de los Expertos Externos acreditados","og_description":"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...","og_url":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/","og_site_name":"Bonatti Compliance","article_publisher":"https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/","article_published_time":"2021-04-17T17:14:27+00:00","article_modified_time":"2024-06-06T13:51:59+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png","type":"image\/png"}],"author":"bonatti","twitter_card":"summary_large_image","twitter_creator":"@BonattiComply","twitter_site":"@BonattiComply","twitter_misc":{"Escrito por":"bonatti","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#article","isPartOf":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/"},"author":{"name":"bonatti","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b"},"headline":"Capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados","datePublished":"2021-04-17T17:14:27+00:00","dateModified":"2024-06-06T13:51:59+00:00","mainEntityOfPage":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/"},"wordCount":651,"commentCount":0,"publisher":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#organization"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage"},"thumbnailUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png","articleSection":["Blanqueo de capitales","Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/","url":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/","name":"Competencia t\u00e9cnica de los Expertos Externos acreditados","isPartOf":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#website"},"primaryImageOfPage":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage"},"thumbnailUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png","datePublished":"2021-04-17T17:14:27+00:00","dateModified":"2024-06-06T13:51:59+00:00","description":"La capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados es un tema al que se hace menci\u00f3n expresa en el Art 28 de la ley...","breadcrumb":{"@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#primaryimage","url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png","contentUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2021\/04\/Experto-Externo-Blanqueo-Capitales-ENAC-Bonatti-2.png","width":560,"height":315,"caption":"Competencia t\u00e9cnica experto externo ENAC Bonatti Blanqueo"},{"@type":"BreadcrumbList","@id":"https:\/\/compliancebonatti.com\/compliance\/competencia-tecnica-expertos-externos-blanqueo-capitales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/compliancebonatti.com\/compliance\/"},{"@type":"ListItem","position":2,"name":"Capacidad y competencia t\u00e9cnica de los Expertos Externos acreditados"}]},{"@type":"WebSite","@id":"https:\/\/compliancebonatti.com\/compliance\/#website","url":"https:\/\/compliancebonatti.com\/compliance\/","name":"Bonatti Compliance","description":"Consultor\u00eda Compliance para empresas","publisher":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compliancebonatti.com\/compliance\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/compliancebonatti.com\/compliance\/#organization","name":"Bonatti Compliance SLP","url":"https:\/\/compliancebonatti.com\/compliance\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/","url":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png","contentUrl":"https:\/\/compliancebonatti.com\/compliance\/wp-content\/uploads\/2019\/06\/bonatti-compliance-logo-1.png","width":600,"height":40,"caption":"Bonatti Compliance SLP"},"image":{"@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bonatti-Compliance-106175060726551\/","https:\/\/x.com\/BonattiComply","https:\/\/www.instagram.com\/bonatticompliance\/","https:\/\/www.linkedin.com\/company\/bonatti-compliance\/about\/"]},{"@type":"Person","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/d0b20692fa4ab31129f31275d8d3082b","name":"bonatti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/compliancebonatti.com\/compliance\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f869a33d81e4c7c61604c50fd1a5ed9?s=96&d=mm&r=g","caption":"bonatti"}}]}},"_links":{"self":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/869"}],"collection":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":4,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"predecessor-version":[{"id":1386,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/posts\/869\/revisions\/1386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/media\/860"}],"wp:attachment":[{"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/compliancebonatti.com\/compliance\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}